{"id":785,"date":"2013-08-27T05:38:18","date_gmt":"2013-08-27T05:38:18","guid":{"rendered":"http:\/\/www.medicina.uanl.mx\/hu\/?p=785"},"modified":"2013-08-27T05:38:18","modified_gmt":"2013-08-27T05:38:18","slug":"prueba-de-funcion-tubarica","status":"publish","type":"post","link":"https:\/\/www.medicina.uanl.mx\/hu\/2013\/08\/27\/prueba-de-funcion-tubarica\/","title":{"rendered":"Prueba de funci\u00f3n tub\u00e1rica"},"content":{"rendered":"\n\t\t\t<div class='et-tabs-container et_sliderfx_fade et_sliderauto_false et_sliderauto_speed_5000 et_slidertype_top_tabs'>\n\t\t\t\t<ul class='et-tabs-control'>\n\t\t\t<li><a href='#'>\n\t\t\t\u00bfEn qu\u00e9 consiste?\n\t\t<\/a><\/li> \n\t\t<li><a href='#'>\n\t\t\t\u00bfD\u00f3nde se realiza?\n\t\t<\/a><\/li>\n\t\t<\/ul> \n\t\t<div class='et-tabs-content'>\n\t\t\t<div class='et-tabs-content-main-wrap'>\n\t\t\t\t<div class='et-tabs-content-wrapper'>\n\t\t\t\t\t<div class='et_slidecontent'>\n\t\t\t<p style=\"text-align: justify;\">Es un examen que permite evaluar la funcionalidad de la trompa de Eustaquio a trav\u00e9s de cambios de presi\u00f3n generados en el canal auditivo externo.<\/p>\n\t\t<\/div> \n\t\t<div class='et_slidecontent'>\n\t\t\t<table id=\"tablepress-otorrino\" class=\"tablepress tablepress-id-otorrino\">\n<tbody>\n<tr class=\"row-1\">\n\t<td class=\"column-1\">Lugar:<\/td><td class=\"column-2\">Hospital Universitario \u0093Dr. Jos\u00e9 Eleuterio Gonz\u00e1lez\u0094\nMadero y Gonzalitos s\/n, Col. Mitras Centro, Monterrey, N.L.\nServicio de Otorrinolaringolog\u00eda Consulta #27, \nEdificio Rodrigo Barrag\u00e1n 1er piso\n\n\n\n<\/td>\n<\/tr>\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Tel\u00e9fono:<\/td><td class=\"column-2\">(81) 8333 4299\n<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Correo:<\/td><td class=\"column-2\">otorrinohu@hotmail.com<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Imagen:<\/td><td class=\"column-2\"><a href=\"http:\/\/www.medicina.uanl.mx\/hu\/wp-content\/uploads\/2010\/12\/2013-07JUL-22-_-CROQUIS-PARA-HORARIOS-DE-ATENCI\u00d3N-AL-P\u00daBLICO.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-200\" alt=\"CROQUIS PARA HORARIOS DE ATENCI\u00d3N AL P\u00daBLICO\" src=\"http:\/\/www.medicina.uanl.mx\/hu\/wp-content\/uploads\/2010\/12\/2013-07JUL-22-_-CROQUIS-PARA-HORARIOS-DE-ATENCI\u00d3N-AL-P\u00daBLICO-287x300.jpg\" width=\"280\" height=\"300\" \/><\/a><\/p><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-otorrino from cache -->\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[26,6,7],"tags":[],"class_list":["post-785","post","type-post","status-publish","format-standard","hentry","category-otorrinolaringologia","category-procedimientos","category-servicio"],"_links":{"self":[{"href":"https:\/\/www.medicina.uanl.mx\/hu\/wp-json\/wp\/v2\/posts\/785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medicina.uanl.mx\/hu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medicina.uanl.mx\/hu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medicina.uanl.mx\/hu\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medicina.uanl.mx\/hu\/wp-json\/wp\/v2\/comments?post=785"}],"version-history":[{"count":1,"href":"https:\/\/www.medicina.uanl.mx\/hu\/wp-json\/wp\/v2\/posts\/785\/revisions"}],"predecessor-version":[{"id":786,"href":"https:\/\/www.medicina.uanl.mx\/hu\/wp-json\/wp\/v2\/posts\/785\/revisions\/786"}],"wp:attachment":[{"href":"https:\/\/www.medicina.uanl.mx\/hu\/wp-json\/wp\/v2\/media?parent=785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medicina.uanl.mx\/hu\/wp-json\/wp\/v2\/categories?post=785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medicina.uanl.mx\/hu\/wp-json\/wp\/v2\/tags?post=785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}