{"id":1326,"date":"2013-11-05T00:02:17","date_gmt":"2013-11-05T00:02:17","guid":{"rendered":"http:\/\/www.medicina.uanl.mx\/hu\/?p=1326"},"modified":"2013-11-05T00:02:17","modified_gmt":"2013-11-05T00:02:17","slug":"sesion-sobre-el-programa-de-donacion-de-organos-y-tejidos-a-residentes-de-nuevo-ingreso","status":"publish","type":"post","link":"https:\/\/www.medicina.uanl.mx\/hu\/2013\/11\/05\/sesion-sobre-el-programa-de-donacion-de-organos-y-tejidos-a-residentes-de-nuevo-ingreso\/","title":{"rendered":"Sesi\u00f3n sobre el programa de Donaci\u00f3n de \u00d3rganos y Tejidos a residentes de nuevo ingreso"},"content":{"rendered":"\n\t\t\t<div class='et-tabs-container et_sliderfx_fade et_sliderauto_false et_sliderauto_speed_5000 et_slidertype_top_tabs'>\n\t\t\t\t<ul class='et-tabs-control'>\n\t\t\t<li><a href='#'>\n\t\t\t\u00bfEn qu\u00e9 consiste?\n\t\t<\/a><\/li> \n\t\t<li><a href='#'>\n\t\t\t\u00bfD\u00f3nde se realiza?\n\t\t<\/a><\/li>\n\t\t<\/ul> \n\t\t<div class='et-tabs-content'>\n\t\t\t<div class='et-tabs-content-main-wrap'>\n\t\t\t\t<div class='et-tabs-content-wrapper'>\n\t\t\t\t\t<div class='et_slidecontent'>\n\t\t\t<p style=\"text-align: justify;\">\nSesi\u00f3n sobre el programa de Donaci\u00f3n de \u00d3rganos y Tejidos a residentes de nuevo ingreso.\n<\/p>\n\t\t<\/div> \n\t\t<div class='et_slidecontent'>\n\t\t\t[table \u201ctransplantes\u201d not found \/]\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[6,7,44],"tags":[],"class_list":["post-1326","post","type-post","status-publish","format-standard","hentry","category-procedimientos","category-servicio","category-transplantes-de-organos-y-tejidos"],"_links":{"self":[{"href":"https:\/\/www.medicina.uanl.mx\/hu\/wp-json\/wp\/v2\/posts\/1326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medicina.uanl.mx\/hu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medicina.uanl.mx\/hu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medicina.uanl.mx\/hu\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medicina.uanl.mx\/hu\/wp-json\/wp\/v2\/comments?post=1326"}],"version-history":[{"count":1,"href":"https:\/\/www.medicina.uanl.mx\/hu\/wp-json\/wp\/v2\/posts\/1326\/revisions"}],"predecessor-version":[{"id":1327,"href":"https:\/\/www.medicina.uanl.mx\/hu\/wp-json\/wp\/v2\/posts\/1326\/revisions\/1327"}],"wp:attachment":[{"href":"https:\/\/www.medicina.uanl.mx\/hu\/wp-json\/wp\/v2\/media?parent=1326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medicina.uanl.mx\/hu\/wp-json\/wp\/v2\/categories?post=1326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medicina.uanl.mx\/hu\/wp-json\/wp\/v2\/tags?post=1326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}